{"id":21822,"count":1,"description":"","link":"https:\/\/eduwisor.com\/blog\/tag\/does-european-university-georgia-have-indian-food\/","name":"Does European University Georgia have Indian food?","slug":"does-european-university-georgia-have-indian-food","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/eduwisor.com\/blog\/wp-json\/wp\/v2\/tags\/21822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eduwisor.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eduwisor.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eduwisor.com\/blog\/wp-json\/wp\/v2\/posts?tags=21822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}