{"id":28263,"count":12,"description":"","link":"https:\/\/eduwisor.com\/blog\/tag\/usmle-from-georgia\/","name":"USMLE from Georgia","slug":"usmle-from-georgia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/eduwisor.com\/blog\/wp-json\/wp\/v2\/tags\/28263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eduwisor.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eduwisor.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eduwisor.com\/blog\/wp-json\/wp\/v2\/posts?tags=28263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}